{"id":1609,"date":"2019-10-29T13:18:21","date_gmt":"2019-10-29T13:18:21","guid":{"rendered":"https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1.jpg"},"modified":"2019-10-29T13:18:21","modified_gmt":"2019-10-29T13:18:21","slug":"proton-t-5-2","status":"inherit","type":"attachment","link":"https:\/\/www.multishred.com\/en\/equipment\/industrial-shredders-disintegrators\/proton-t-5-2\/","title":{"rendered":"Proton-T-5"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-1609","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proton-T-5 | Multishred<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.multishred.com\/en\/equipment\/industrial-shredders-disintegrators\/proton-t-5-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proton-T-5 | Multishred\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.multishred.com\/en\/equipment\/industrial-shredders-disintegrators\/proton-t-5-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Multishred\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/equipment\\\/industrial-shredders-disintegrators\\\/proton-t-5-2\\\/\",\"url\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/equipment\\\/industrial-shredders-disintegrators\\\/proton-t-5-2\\\/\",\"name\":\"Proton-T-5 | Multishred\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/#website\"},\"datePublished\":\"2019-10-29T13:18:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/equipment\\\/industrial-shredders-disintegrators\\\/proton-t-5-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.multishred.com\\\/en\\\/equipment\\\/industrial-shredders-disintegrators\\\/proton-t-5-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/equipment\\\/industrial-shredders-disintegrators\\\/proton-t-5-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equipment\",\"item\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/equipment\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Industrial Shredding and Destruction Equipment\",\"item\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/equipment\\\/industrial-shredders-disintegrators\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Proton-T-5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/\",\"name\":\"Multishred\",\"description\":\"High Security Shredding and Destruction Services and Equipment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/#organization\",\"name\":\"Multishred\",\"url\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.multishred.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-multishred-2x.png\",\"contentUrl\":\"https:\\\/\\\/www.multishred.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-multishred-2x.png\",\"width\":278,\"height\":71,\"caption\":\"Multishred\"},\"image\":{\"@id\":\"https:\\\/\\\/www.multishred.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proton-T-5 | Multishred","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.multishred.com\/en\/equipment\/industrial-shredders-disintegrators\/proton-t-5-2\/","og_locale":"en_US","og_type":"article","og_title":"Proton-T-5 | Multishred","og_url":"https:\/\/www.multishred.com\/en\/equipment\/industrial-shredders-disintegrators\/proton-t-5-2\/","og_site_name":"Multishred","og_image":[{"width":420,"height":420,"url":"https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.multishred.com\/en\/equipment\/industrial-shredders-disintegrators\/proton-t-5-2\/","url":"https:\/\/www.multishred.com\/en\/equipment\/industrial-shredders-disintegrators\/proton-t-5-2\/","name":"Proton-T-5 | Multishred","isPartOf":{"@id":"https:\/\/www.multishred.com\/en\/#website"},"datePublished":"2019-10-29T13:18:21+00:00","breadcrumb":{"@id":"https:\/\/www.multishred.com\/en\/equipment\/industrial-shredders-disintegrators\/proton-t-5-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.multishred.com\/en\/equipment\/industrial-shredders-disintegrators\/proton-t-5-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.multishred.com\/en\/equipment\/industrial-shredders-disintegrators\/proton-t-5-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.multishred.com\/en\/"},{"@type":"ListItem","position":2,"name":"Equipment","item":"https:\/\/www.multishred.com\/en\/equipment\/"},{"@type":"ListItem","position":3,"name":"Industrial Shredding and Destruction Equipment","item":"https:\/\/www.multishred.com\/en\/equipment\/industrial-shredders-disintegrators\/"},{"@type":"ListItem","position":4,"name":"Proton-T-5"}]},{"@type":"WebSite","@id":"https:\/\/www.multishred.com\/en\/#website","url":"https:\/\/www.multishred.com\/en\/","name":"Multishred","description":"High Security Shredding and Destruction Services and Equipment","publisher":{"@id":"https:\/\/www.multishred.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.multishred.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.multishred.com\/en\/#organization","name":"Multishred","url":"https:\/\/www.multishred.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.multishred.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.multishred.com\/wp-content\/uploads\/2017\/04\/logo-multishred-2x.png","contentUrl":"https:\/\/www.multishred.com\/wp-content\/uploads\/2017\/04\/logo-multishred-2x.png","width":278,"height":71,"caption":"Multishred"},"image":{"@id":"https:\/\/www.multishred.com\/en\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a rel=\"prettyPhoto[pp_gal]\" href='https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1-300x300.jpg 300w, https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1-150x150.jpg 150w, https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1-80x80.jpg 80w, https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1.jpg 420w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":420,"height":420,"file":"2019\/10\/Proton-T-5-1.jpg","sizes":{"thumbnail":{"file":"Proton-T-5-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1-150x150.jpg"},"medium":{"file":"Proton-T-5-1-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1-300x300.jpg"},"mini":{"file":"Proton-T-5-1-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1-80x80.jpg"},"portfolio":{"file":"Proton-T-5-1-420x400.jpg","width":420,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1-420x400.jpg"},"full":{"file":"Proton-T-5-1.jpg","width":420,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":436,"source_url":"https:\/\/www.multishred.com\/wp-content\/uploads\/2019\/10\/Proton-T-5-1.jpg","_links":{"self":[{"href":"https:\/\/www.multishred.com\/en\/wp-json\/wp\/v2\/media\/1609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.multishred.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.multishred.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.multishred.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.multishred.com\/en\/wp-json\/wp\/v2\/comments?post=1609"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":436,"href":"https:\/\/www.multishred.com\/en\/wp-json\/wp\/v2\/pages\/436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}